{"id":24494,"date":"2025-04-13T17:41:49","date_gmt":"2025-04-13T17:41:49","guid":{"rendered":"https:\/\/bestresearchchemical.com\/?post_type=product&#038;p=24494"},"modified":"2026-06-29T14:45:17","modified_gmt":"2026-06-29T14:45:17","slug":"tubes-de-5-ml","status":"publish","type":"product","link":"https:\/\/bestresearchchemical.com\/fr\/produit\/tubes-de-5-ml\/","title":{"rendered":"Tube de 5 ml de 5-MAPB"},"content":{"rendered":"<h2 class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">5-MAPB 5ml Tube \u2013 Research Solution for Serotonergic Studies<\/span><\/span><\/strong><\/h2>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Description du produit<\/span><\/span><\/strong><\/h3>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">5 mapb, This <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">5-MAPB 5ml tube<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0contains a\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">sterile, precisely dosed solution<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0of 5-Methoxy-aminopropylbenzofuran, specially developed for\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">neuropharmacological research into serotonergic systems<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> .<\/span><\/span><\/p>\n<p class=\"ds-markdown-paragraph\">\u2714\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">5ml solution<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0(concentration: 5mg\/ml) <\/span><\/span><br \/>\n\u2714\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Pharmaceutical grade<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0sterile aqueous solution <\/span><\/span><br \/>\n\u2714\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">pH balanced<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0(6.5-7.0) for optimal stability <\/span><\/span><br \/>\n\u2714\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Airtight glass tube<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0with rubber septum<\/span><\/span><\/p>\n<hr \/>\n<h2><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">R\u00e9sum\u00e9 du rapport de laboratoire (COA)<\/span><\/span><\/strong><\/h2>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">*Batch #5MAPB-0326-NL | Tested by Serotonin Research Labs* <\/span><\/span><br \/>\n\u2714\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">5.1mg\/ml \u00b10.2mg<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0(LC-MS\/MS) <\/span><\/span><br \/>\n\u2714\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">98.9% chemical purity <\/span><\/span><\/strong><br \/>\n\u2714\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">No endotoxins detectable <\/span><\/span><\/strong><br \/>\n\u2714\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">0.22\u03bcm filtered<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0for sterility<\/span><\/span><\/p>\n<hr \/>\n<h2><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Applications de recherche recommand\u00e9es<\/span><\/span><\/strong><\/h2>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">1. Examen neuropsychiatrique<\/span><\/span><\/strong><\/h3>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">SERT transporter inhibition studies<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Comparative research with MDMA<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">2. Behavioral pharmacology<\/span><\/span><\/strong><\/h3>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Social interaction models<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Anxiety reduction paradigms<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">3. Neuroprotection Studies<\/span><\/span><\/strong><\/h3>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Oxidative stress evaluation<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Thermal hyperthermia research<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<hr \/>\n<h2><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Protocole d&#039;utilisation<\/span><\/span><\/strong><\/h2>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Methods of administration<\/span><\/span><\/strong><\/h3>\n<ol start=\"1\">\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Intraperitoneal<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> : 0.1 ml\/100 g body weight<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Subcutaneous<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> : Maximum 0.2 ml per injection site<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Oral<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> : Dilute in 5ml water (animal studies)<\/span><\/span><\/p>\n<\/li>\n<\/ol>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Directives posologiques<\/span><\/span><\/strong><\/h3>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Faible<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> : 1mg\/kg (0.2ml\/kg)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Moyen<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> : 3mg\/kg (0.6ml\/kg)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Haut<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> : 5 mg\/kg (1 ml\/kg) \u2013 max 1x\/semaine<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<hr \/>\n<h2><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Risks &amp; Limitations<\/span><\/span><\/strong><\/h2>\n<p class=\"ds-markdown-paragraph\">\u26a0\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Serotonin Syndrome Risk<\/span><\/span><\/strong><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">When combined with MAO inhibitors<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<p class=\"ds-markdown-paragraph\">\u26a0\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Hyperthermia Danger<\/span><\/span><\/strong><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Maintain ambient temperature \u226422\u00b0C<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<p class=\"ds-markdown-paragraph\">\u26a0\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Statut juridique<\/span><\/span><\/strong><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Opium Act Appendix I (Netherlands)<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<p class=\"ds-markdown-paragraph\">\u26a0\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Dur\u00e9e de conservation<\/span><\/span><\/strong><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">3 months at room temperature, 6 months at 4\u00b0C<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<hr \/>\n<h2><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Foire aux questions (FAQ)<\/span><\/span><\/strong><\/h2>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Q: How does 5-MAPB compare to 6-APB?<\/span><\/span><\/strong><\/h3>\n<div class=\"markdown-table-wrapper\">\n<table>\n<thead>\n<tr>\n<th><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Param\u00e8tre<\/span><\/span><\/th>\n<th><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">5-MAPB<\/span><\/span><\/th>\n<th><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">6-APB<\/span><\/span><\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Potentiel<\/span><\/span><\/td>\n<td><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u2605\u2605\u2605\u2606<\/span><\/span><\/td>\n<td><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u2605\u2605\u2605\u2605\u2606<\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Dur\u00e9e d&#039;action<\/span><\/span><\/td>\n<td><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">4h-6h<\/span><\/span><\/td>\n<td><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">6h-8h<\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">S\u00e9lectivit\u00e9 SERT<\/span><\/span><\/td>\n<td><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">85%<\/span><\/span><\/td>\n<td><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">65%<\/span><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Q: Can I give this intravenously?<\/span><\/span><\/strong><\/h3>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">UN:\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Not recommended<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0&#8211; Only tested for IP\/SC routes<\/span><\/span><\/p>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Q: Suitable for microdialysis?<\/span><\/span><\/strong><\/h3>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">UN:\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Oui<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0&#8211; Dilute to 2\u03bcg\/ml in aCSF<\/span><\/span><\/p>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Q : Que se passe-t-il en cas d\u2019exposition accidentelle ?<\/span><\/span><\/strong><\/h3>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">A: Immediate flushing + benzodiazepine administration<\/span><\/span><\/p>\n<hr \/>\n<h2><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Protocole de r\u00e9duction des risques<\/span><\/span><\/strong><\/h2>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u2022\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Temperature monitoring<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0obligatoire <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u2022\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Ventilation<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0during manipulation <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u2022\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Dose logger<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0with timestamp<\/span><\/span><\/p>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">*Avertissement\u00a0: R\u00e9serv\u00e9 \u00e0 la recherche scientifique l\u00e9gitime. Non destin\u00e9 \u00e0 l&#039;usage humain. R\u00e9serv\u00e9 aux personnes de 21\u00a0ans et plus. Magasin ferm\u00e9 \u00e0 cl\u00e9.* <\/span><\/span><a href=\"https:\/\/bestresearchchemical.com\/fr\/boutique\/iboga-ibogaine\/ecorce-de-racine-diboga\/\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u00e9corce de racine d&#039;iboga<\/span><\/span><\/a><a href=\"https:\/\/bestresearchchemical.com\/fr\/boutique\/iboga-ibogaine\/acheter-de-libogaine-hcl\/\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u200b acheter de l&#039;iboga\u00efne hcl en ligne<\/span><\/span><\/a><a href=\"https:\/\/bestresearchchemical.com\/fr\/boutique\/lysergamides\/1cp-lsd-150-mcg-2\/\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">1 cp de LSD <\/span><\/span><\/a><a href=\"https:\/\/bestresearchchemical.com\/fr\/boutique\/granules\/o-dsmt-50-mg-granules\/\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">o-dsmt <\/span><\/span><\/a><a href=\"https:\/\/bestresearchchemical.com\/fr\/boutique\/lysergamides\/buvards-1v-lsd-150-mcg\/\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">1vlsd<\/span><\/span><\/a><\/p>\n<ul>\n<li><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<h2><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">5-MAPB 5ml Tube<\/span><\/span><\/strong><\/h2>","protected":false},"featured_media":29294,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[82],"product_cat":[555],"product_tag":[109,326],"class_list":["post-24494","product","type-product","status-publish","has-post-thumbnail","product_brand-research-chemical","product_cat-b2b","product_tag-5-mapb","product_tag-nl","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/bestresearchchemical.com\/fr\/wp-json\/wp\/v2\/product\/24494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bestresearchchemical.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bestresearchchemical.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bestresearchchemical.com\/fr\/wp-json\/wp\/v2\/comments?post=24494"}],"version-history":[{"count":5,"href":"https:\/\/bestresearchchemical.com\/fr\/wp-json\/wp\/v2\/product\/24494\/revisions"}],"predecessor-version":[{"id":28435,"href":"https:\/\/bestresearchchemical.com\/fr\/wp-json\/wp\/v2\/product\/24494\/revisions\/28435"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bestresearchchemical.com\/fr\/wp-json\/wp\/v2\/media\/29294"}],"wp:attachment":[{"href":"https:\/\/bestresearchchemical.com\/fr\/wp-json\/wp\/v2\/media?parent=24494"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bestresearchchemical.com\/fr\/wp-json\/wp\/v2\/product_brand?post=24494"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bestresearchchemical.com\/fr\/wp-json\/wp\/v2\/product_cat?post=24494"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bestresearchchemical.com\/fr\/wp-json\/wp\/v2\/product_tag?post=24494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}