{"id":24037,"date":"2025-04-13T17:40:56","date_gmt":"2025-04-13T17:40:56","guid":{"rendered":"https:\/\/bestresearchchemical.com\/?post_type=product&#038;p=24037"},"modified":"2026-06-29T14:47:06","modified_gmt":"2026-06-29T14:47:06","slug":"mdphp-kopen-2","status":"publish","type":"product","link":"https:\/\/bestresearchchemical.com\/da\/vare\/mdphp-kopen-2\/","title":{"rendered":"MDPHP-pulver (fri base)"},"content":{"rendered":"<h1 class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">MDPHP Powder (Freebase) \u2013 Premium Quality Research Chemical<\/span><\/span><\/strong><\/h1>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">buy mdphp<\/span><\/span><\/p>\n<h3><strong>\ud83d\udd2c<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Produktspecifikationer:<\/span><\/span><\/strong><\/h3>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Substance name:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0MDPHP (methylendioxypyrovaleron)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Form:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Crystalline powder (freebase)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Renhed:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0\u226598% (HPLC verified)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Farve:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0White to light colored<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Opl\u00f8selighed:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Soluble in organic solvents<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Stability:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Long term stable when stored correctly<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<h3><strong>\ud83d\udca1<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">N\u00f8glefunktioner:<\/span><\/span><\/strong><\/h3>\n<p class=\"ds-markdown-paragraph\">\u2714\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">High purity quality<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0\u2013 Ideal for analytical and pharmacological research <\/span><\/span><br \/>\n\u2714\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Freebase form<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0\u2013 Suitable for various laboratory applications <\/span><\/span><br \/>\n\u2714\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Detailed analyses available<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> (HPLC, GC\/MS) on request, buy mdphp<\/span><\/span><\/p>\n<h3><strong>\ud83e\uddea<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Recommended Research Areas:<\/span><\/span><\/strong><\/h3>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Neurokemiske studier<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Receptor interaction research<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Metabolic pathway analysis<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Sammenlignende farmakologiske studier<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<h3><strong>\u26a0\ufe0f<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Sikkerhedsoplysninger:<\/span><\/span><\/strong><\/h3>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">FOR RESEARCH PURPOSES ONLY<\/span><\/span><\/strong><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Not intended for human or animal consumption<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Mandatory: personal protective equipment (gloves, lab coat, safety glasses)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">For use only in a controlled laboratory environment<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<h3><strong>\ud83c\udf21<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Opbevaringsr\u00e5d:<\/span><\/span><\/strong><\/h3>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Store in an airtight container<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Store in a cool, dark place (2-8\u00b0C for optimal shelf life)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Protect from moisture and direct sunlight<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<h3><strong>\ud83d\udce6<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Emballagemuligheder:<\/span><\/span><\/strong><\/h3>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">1 gram<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0(standard)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">5 grams<\/span><\/span><\/strong><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">10 grams and larger quantities<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0on request<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<h3><strong>\ud83d\udeab<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Juridisk status:<\/span><\/span><\/strong><\/h3>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Sold exclusively to qualified researchers and institutions<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Buyer is responsible for compliance with local laws, mdphp buy<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<h3><strong>\ud83d\udccc<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Remark:<\/span><\/span><\/strong><\/h3>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">MSDS (Material Safety Data Sheet) available upon request<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Technical support for research questions, <\/span><\/span><a href=\"https:\/\/bestresearchchemical.com\/da\/butik\/iboga-ibogain\/kob-ibogaine-hcl-online\/\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">K\u00f8b Ibogaine HCL <\/span><\/span><\/a><a href=\"https:\/\/bestresearchchemical.com\/da\/butik\/iboga-ibogain\/iboga-rodbark\/\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Iboga rodbark <\/span><\/span><\/a><a href=\"https:\/\/bestresearchchemical.com\/da\/butik\/lysergamider\/1cp-lsd\/\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">1cP-LSD 150 MCG Kunstpapirkugler <\/span><\/span><\/a><a href=\"https:\/\/bestresearchchemical.com\/da\/butik\/pellets\/o-dsmt-50-mg-pellets\/\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">O-DSMT 50 mg pellets <\/span><\/span><\/a><a href=\"https:\/\/bestresearchchemical.com\/da\/butik\/lysergamider\/1v-lsd-150-mcg-blotters\/\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">1V-LSD 150 MCG Blotters<\/span><\/span><\/a><\/p>\n<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<h2><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">MDPHP Powder (freebase)<\/span><\/span><\/strong><\/h2>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">CAS No: 776994-64-0 <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Formula: C17H23NO3 FREEBASE <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Molar mass: 289.375 g mol <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Renhed: \u226598%<\/span><\/span><\/p>","protected":false},"featured_media":29406,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[82],"product_cat":[488],"product_tag":[560,559,581,326],"class_list":["post-24037","product","type-product","status-publish","has-post-thumbnail","product_brand-research-chemical","product_cat-verboden","product_tag-mdphp-freebase-kopen","product_tag-mdphp-kopen","product_tag-mdphp-poeder","product_tag-nl","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/bestresearchchemical.com\/da\/wp-json\/wp\/v2\/product\/24037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bestresearchchemical.com\/da\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bestresearchchemical.com\/da\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bestresearchchemical.com\/da\/wp-json\/wp\/v2\/comments?post=24037"}],"version-history":[{"count":5,"href":"https:\/\/bestresearchchemical.com\/da\/wp-json\/wp\/v2\/product\/24037\/revisions"}],"predecessor-version":[{"id":28440,"href":"https:\/\/bestresearchchemical.com\/da\/wp-json\/wp\/v2\/product\/24037\/revisions\/28440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bestresearchchemical.com\/da\/wp-json\/wp\/v2\/media\/29406"}],"wp:attachment":[{"href":"https:\/\/bestresearchchemical.com\/da\/wp-json\/wp\/v2\/media?parent=24037"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bestresearchchemical.com\/da\/wp-json\/wp\/v2\/product_brand?post=24037"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bestresearchchemical.com\/da\/wp-json\/wp\/v2\/product_cat?post=24037"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bestresearchchemical.com\/da\/wp-json\/wp\/v2\/product_tag?post=24037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}